{"id":1006124,"date":"2024-03-20T17:24:54","date_gmt":"2024-03-20T20:24:54","guid":{"rendered":"https:\/\/novosite.psr-inc.com\/noticia\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/"},"modified":"2024-03-20T18:16:38","modified_gmt":"2024-03-20T21:16:38","slug":"entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica","status":"publish","type":"noticia","link":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/","title":{"rendered":"Entienda por qu\u00e9 Am\u00e9rica Latina es un hub ideal para consolidar la transici\u00f3n energ\u00e9tica"},"content":{"rendered":"<p><em>Expertos de PSR, el mercado y la academia debaten enel ELAU 2024 los desaf\u00edos de planificar la operaci\u00f3n y expansi\u00f3n de los sistemas el\u00e9ctricos con la expansi\u00f3n de las fuentes renovables<\/em><\/p>\n<p>Am\u00e9rica Latina cuenta con los recursos naturales, los mecanismos regulatorios y las condiciones de expansi\u00f3n de infraestructura para enfrentar los desaf\u00edos inherentes al cambio clim\u00e1tico y la transici\u00f3n energ\u00e9tica. As\u00ed lo afirma Mario Veiga, fundador y Director de Innovaci\u00f3n de PSR.<\/p>\n<p>\u00abAm\u00e9rica Latina tiene condiciones excepcionales en t\u00e9rminos de una red de transmisi\u00f3n planificada centralmente y mecanismos para construir infraestructura de transmisi\u00f3n. Tenemos represas hidroel\u00e9ctricas que act\u00faan como grandes bater\u00edas de agua y contamos con abundantes recursos energ\u00e9ticos\u00bb, dijo Veiga, durante una mesa redonda sobre los desaf\u00edos de la planificaci\u00f3n de la operaci\u00f3n y expansi\u00f3n de sistemas el\u00e9ctricos con alta penetraci\u00f3n de renovables, que marc\u00f3 la apertura del Encuentro Latinoamericano de Usuarios de PSR, que se celebra entre el 18 y el 22 de marzo en la Ciudad de Panam\u00e1.<\/p>\n<div style=\"text-align: center;\">\n<iframe title=\"Mesa Redonda - Apertura del Encuentro Latinoamericano de Usuarios de PSR 2024\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/5MBoCTI4NBw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div>\n<p>Veiga record\u00f3 que el 75% de las emisiones de gases de efecto invernadero en el mundo son causadas por el sector energ\u00e9tico. Subray\u00f3 que la industria el\u00e9ctrica es capaz de contribuir a la descarbonizaci\u00f3n del propio sector y de la econom\u00eda en su conjunto.<\/p>\n<p>\u00abEl reto ahora es gestionar la gran variabilidad de la generaci\u00f3n e\u00f3lica y solar. Necesitamos almacenamiento y reserva din\u00e1mica probabil\u00edstica. Adem\u00e1s, necesitamos transmisi\u00f3n. La falta de transmisi\u00f3n podr\u00eda poner en peligro el crecimiento de la e\u00f3lica y la solar\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Ricardo Mota, director general del Centro Nacional de Control de Energ\u00eda (CENACE) de M\u00e9xico, estuvo presente en la mesa redonda y dijo que hab\u00eda consenso sobre la necesidad de controlar las emisiones, teniendo en cuenta que el sistema mexicano depende en gran medida del gas natural, que representa alrededor del 60% de la matriz energ\u00e9tica del pa\u00eds. \u00abEstamos reduciendo gradualmente nuestro consumo de carb\u00f3n y otros combustibles l\u00edquidos\u00bb.<\/p>\n<p>Mota tambi\u00e9n destac\u00f3 la importancia de la alianza del CENACE con PSR, responsable de suministrar modelos computacionales para ayudar a planear la expansi\u00f3n y operaci\u00f3n del sistema el\u00e9ctrico mexicano. \u00abSeguimos trabajando con PSR porque todos los resultados que hemos obtenido son muy valiosos\u00bb.<\/p>\n<p>En la misma l\u00ednea, Luiz Barroso, CEO de PSR, a\u00f1adi\u00f3 que los modelos desempe\u00f1an un papel importante en la operaci\u00f3n del sistema al permitir a los operadores definir nuevos productos en funci\u00f3n de las necesidades, como la flexibilidad. \u00abHoy en d\u00eda se habla mucho de flexibilidad operativa. Muchos pa\u00edses, como Estados Unidos, ya est\u00e1n contratando productos espec\u00edficos de flexibilidad\u00bb, explic\u00f3.<\/p>\n<p>En cuanto a la planificaci\u00f3n, Barroso a\u00f1adi\u00f3 que es importante que las restricciones operativas est\u00e9n muy bien representadas en los modelos para que el planificador pueda ofrecer un plan m\u00e1s adecuado para el sistema. Y sobre el cambio clim\u00e1tico, se\u00f1al\u00f3 que durante el ELAU se debatir\u00e1 c\u00f3mo representar los fen\u00f3menos clim\u00e1ticos en los modelos computacionales.<\/p>\n<p>Siguiendo con el tema del cambio clim\u00e1tico, Rodrigo Moreno, profesor de la Universidad de Chile e investigador del Imperial College de Londres, que tambi\u00e9n particip\u00f3 de la mesa redonda, destac\u00f3 la importancia del mundo acad\u00e9mico en este debate y se\u00f1al\u00f3 que uno de los mayores retos a los que se enfrenta hoy el sector energ\u00e9tico es como capturar adecuadamente las incertidumbres en los modelos. Tambi\u00e9n hizo hincapi\u00e9 en la importancia de la resiliencia de las redes.<\/p>\n<p>La mesa redonda fue moderada por Raphael Chabar, director ejecutivo de PSR y coordinador general t\u00e9cnico y comercial de los equipos de modelizaci\u00f3n computacional de PSR y \u00e1reas aplicadas al sector energ\u00e9tico. Chabar encabeza el equipo de expertos de PSR presentes en ELAU.<\/p>\n<p>ELAU cuenta con un centenar de participantes inscritos, procedentes de m\u00e1s de una decena de pa\u00edses, con perfiles muy variados, entre los que se encuentran generadores y organizaciones de planificaci\u00f3n y explotaci\u00f3n, entre otros.<\/p>\n<p>Para m\u00e1s informaci\u00f3n sobre la reuni\u00f3n y consultar el programa completo, visite la p\u00e1gina web del evento: <a href=\"https:\/\/elau2024.psr-inc.com\/\">https:\/\/elau2024.psr-inc.com\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expertos de PSR, el mercado y la academia debaten enel ELAU 2024 los desaf\u00edos de planificar la operaci\u00f3n y expansi\u00f3n de los sistemas el\u00e9ctricos con la expansi\u00f3n de las fuentes renovables Am\u00e9rica Latina cuenta con los recursos naturales, los mecanismos regulatorios y las condiciones de expansi\u00f3n de infraestructura para enfrentar los desaf\u00edos inherentes al cambio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":999137,"template":"","meta":{"_acf_changed":false},"categories":[],"class_list":["post-1006124","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noticias\" \/>\n<meta property=\"og:description\" content=\"Expertos de PSR, el mercado y la academia debaten enel ELAU 2024 los desaf\u00edos de planificar la operaci\u00f3n y expansi\u00f3n de los sistemas el\u00e9ctricos con la expansi\u00f3n de las fuentes renovables Am\u00e9rica Latina cuenta con los recursos naturales, los mecanismos regulatorios y las condiciones de expansi\u00f3n de infraestructura para enfrentar los desaf\u00edos inherentes al cambio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/\" \/>\n<meta property=\"og:site_name\" content=\"PSR Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psrenergy\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T21:16:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png\" \/>\n\t<meta property=\"og:image:width\" content=\"941\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@psrenergy\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/\",\"name\":\"Noticias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png\",\"datePublished\":\"2024-03-20T20:24:54+00:00\",\"dateModified\":\"2024-03-20T21:16:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png\",\"width\":941,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticia-es\\\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/noticias-antigo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entienda por qu\u00e9 Am\u00e9rica Latina es un hub ideal para consolidar la transici\u00f3n energ\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/\",\"name\":\"PSR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/#organization\"},\"alternateName\":\"PSR Energy Consulting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/#organization\",\"name\":\"PSR\",\"alternateName\":\"PSR Energy Consulting\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"width\":1056,\"height\":816,\"caption\":\"PSR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/psrenergy\",\"https:\\\/\\\/x.com\\\/psrenergy\",\"https:\\\/\\\/www.instagram.com\\\/psrenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psrenergy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/","og_locale":"es_ES","og_type":"article","og_title":"Noticias","og_description":"Expertos de PSR, el mercado y la academia debaten enel ELAU 2024 los desaf\u00edos de planificar la operaci\u00f3n y expansi\u00f3n de los sistemas el\u00e9ctricos con la expansi\u00f3n de las fuentes renovables Am\u00e9rica Latina cuenta con los recursos naturales, los mecanismos regulatorios y las condiciones de expansi\u00f3n de infraestructura para enfrentar los desaf\u00edos inherentes al cambio [&hellip;]","og_url":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/","og_site_name":"PSR Energy","article_publisher":"https:\/\/www.facebook.com\/psrenergy","article_modified_time":"2024-03-20T21:16:38+00:00","og_image":[{"width":941,"height":681,"url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@psrenergy","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/","url":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/","name":"Noticias","isPartOf":{"@id":"https:\/\/www.psr-inc.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/#primaryimage"},"image":{"@id":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png","datePublished":"2024-03-20T20:24:54+00:00","dateModified":"2024-03-20T21:16:38+00:00","breadcrumb":{"@id":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/#primaryimage","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/POR-header-sitenovo-psr-transicao-energetica-am-latina.png","width":941,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/www.psr-inc.com\/es\/noticia-es\/entienda-por-que-america-latina-es-un-hub-ideal-para-consolidar-la-transicion-energetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psr-inc.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www.psr-inc.com\/es\/noticias-antigo\/"},{"@type":"ListItem","position":3,"name":"Entienda por qu\u00e9 Am\u00e9rica Latina es un hub ideal para consolidar la transici\u00f3n energ\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/www.psr-inc.com\/es\/#website","url":"https:\/\/www.psr-inc.com\/es\/","name":"PSR","description":"","publisher":{"@id":"https:\/\/www.psr-inc.com\/es\/#organization"},"alternateName":"PSR Energy Consulting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psr-inc.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.psr-inc.com\/es\/#organization","name":"PSR","alternateName":"PSR Energy Consulting","url":"https:\/\/www.psr-inc.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.psr-inc.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","width":1056,"height":816,"caption":"PSR"},"image":{"@id":"https:\/\/www.psr-inc.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/psrenergy","https:\/\/x.com\/psrenergy","https:\/\/www.instagram.com\/psrenergy\/","https:\/\/www.linkedin.com\/company\/psrenergy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/noticia\/1006124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/noticia\/1006124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/media\/999137"}],"wp:attachment":[{"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/media?parent=1006124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psr-inc.com\/es\/wp-json\/wp\/v2\/categories?post=1006124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}