{"id":1005569,"date":"2022-04-28T16:00:43","date_gmt":"2022-04-28T19:00:43","guid":{"rendered":"https:\/\/novosite.psr-inc.com\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/"},"modified":"2022-04-28T16:00:43","modified_gmt":"2022-04-28T19:00:43","slug":"planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr","status":"publish","type":"noticia","link":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/","title":{"rendered":"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR"},"content":{"rendered":"<p>H\u00e1 pouco mais de dois anos, a PSR venceu uma concorr\u00eancia internacional para desenvolver um modelo avan\u00e7ado de an\u00e1lise energ\u00e9tica para a regi\u00e3o do Pacific Northwest norte americano. Esta regi\u00e3o possui um conjunto de fontes de gera\u00e7\u00e3o bastante diversificado, incluindo as hidrel\u00e9tricas da Bonneville Power Administration (BPA), uma grande capacidade e\u00f3lica e de gera\u00e7\u00e3o a g\u00e1s natural, e interconex\u00f5es el\u00e9tricas com a Calif\u00f3rnia, outros estados da Costa Oeste e o Canad\u00e1. As especifica\u00e7\u00f5es do modelo, chamado Genesys (GENeration Evaluation SYStem) eram extremamente ambiciosas: otimizar a opera\u00e7\u00e3o do sistema de gera\u00e7\u00e3o e interconex\u00f5es considerando detalhes operativos hor\u00e1rios de todas as fontes, a incerteza da produ\u00e7\u00e3o e\u00f3lica e hidrel\u00e9trica e as restri\u00e7\u00f5es operativas e ambientais das hidrel\u00e9tricas, das mais complexas do mundo, para milhares de cen\u00e1rios. Para atender as especifica\u00e7\u00f5es, seria necess\u00e1rio resolver centenas de milh\u00f5es de problemas de otimiza\u00e7\u00e3o de grande porte, um recorde mundial para modelos deste tipo.<\/p>\n<p>&nbsp;<\/p>\n<p>A solu\u00e7\u00e3o proposta pela PSR para o Genesys se baseou em tr\u00eas componentes na fronteira de algoritmos e de computa\u00e7\u00e3o de alto desempenho: (i) adapta\u00e7\u00e3o de seu modelo operativo estoc\u00e1stico SDDP, utilizado em dezenas de pa\u00edses de todos os continentes; (ii) uma arquitetura de computa\u00e7\u00e3o em nuvem com dezenas de milhares de processadores atuando em paralelo para realizar todas as an\u00e1lises em poucas horas; (iii) um ambiente tamb\u00e9m em nuvem, PSR Core, que integra entrada dos dados, execu\u00e7\u00e3o dos modelos e an\u00e1lise gr\u00e1fica distribu\u00edda dos arquivos de resultados, que cont\u00e9m dezenas de Terabytes de dados.<\/p>\n<p>&nbsp;<\/p>\n<p>O modelo foi amplamente testado e validado por cerca de um ano em conjunto com a equipe t\u00e9cnica do NWPCC (Northwest Power and Conservation Council), respons\u00e1vel pelo projeto, e em apresenta\u00e7\u00f5es para dezenas de empresas e ag\u00eancias da regi\u00e3o, como a BPA e o US Army Corps of Engineers. Em meados do ano passado o Genesys foi usado oficialmente para preparar o recentemente publicado 2021 Northwest Power Plan, plano regional de expans\u00e3o dos estados de Idaho, Montana, Oregon e Washington, cujo objetivo \u00e9 equilibrar as necessidades energ\u00e9ticas e ambientais da regi\u00e3o, com destaque na preserva\u00e7\u00e3o dos benef\u00edcios do Rio Columbia para o futuro (<a href=\"https:\/\/www.nwcouncil.org\/about\">https:\/\/www.nwcouncil.org\/about<\/a>). Os cen\u00e1rios analisados inclu\u00edram mudan\u00e7as no portf\u00f3lio dos principais agentes com a entrada de renov\u00e1veis, robustez na efici\u00eancia energ\u00e9tica, depend\u00eancia de recursos externos e caminhos para a descarboniza\u00e7\u00e3o (<a href=\"https:\/\/www.nwcouncil.org\/2021-northwest-power-plan\/\">https:\/\/www.nwcouncil.org\/2021-northwest-power-plan\/<\/a>).<\/p>\n<p>O plano analisou mais de 12 mil cen\u00e1rios, utilizando 24 mil processadores em nuvem. Em dois dias foram utilizados quase 200 mil horas de CPU e foram resolvidos mais de 200 milh\u00f5es de problemas de otimiza\u00e7\u00e3o inteira de grande tamanho (milh\u00f5es de vari\u00e1veis de decis\u00e3o e restri\u00e7\u00f5es) resultando em mais de 10 terabytes de dados para p\u00f3s processamento no PSR Core.<\/p>\n<p>John Ollis, coordenador de planejamento e an\u00e1lise do NWPCC, comenta \u201cA PSR foi muito al\u00e9m para garantir que tenhamos uma ferramenta de \u00faltima gera\u00e7\u00e3o para responder \u00e0 perguntas que antes pens\u00e1vamos fora do \u00e2mbito do que poderia ser modelado. Durante o mais recente plano de energia regional do NWPCC, a PSR forneceu assist\u00eancia inestim\u00e1vel ao time do NWPCC, criando uma ferramenta para ajudar a entender as opera\u00e7\u00f5es de um sistema hidrel\u00e9trico fortemente restrito sob diferentes pol\u00edticas e mercados de energia em r\u00e1pida mudan\u00e7a, dominados por energia renov\u00e1vel. As ferramentas e a equipe de PSR superaram minhas expectativas v\u00e1rias vezes e eu as recomendaria a qualquer pessoa.\u201d<\/p>\n<p>Segundo Joaquim Garcia, que liderou o desenvolvimento dos algoritmos do Genesys, \u201co \u00eaxito deste projeto se deve \u00e0 equipe multidisciplinar da PSR, que alia o melhor da teoria matem\u00e1tica, computa\u00e7\u00e3o de alto desempenho, bases de dado de grande porte, computa\u00e7\u00e3o em nuvem e ferramentas gr\u00e1ficas\u201d. Para Mario Veiga, fundador e atual Chief Innovation Officer da PSR, \u201cO Genesys ilustra a alta qualidade das ferramentas da PSR, que combinam as mais modernas tecnologias computacionais e matem\u00e1ticas, e que h\u00e1 mais de trinta anos tem sido exportadas para mais de setenta pa\u00edses de todos os continentes\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 pouco mais de dois anos, a PSR venceu uma concorr\u00eancia internacional para desenvolver um modelo avan\u00e7ado de an\u00e1lise energ\u00e9tica para a regi\u00e3o do Pacific Northwest norte americano. Esta regi\u00e3o possui um conjunto de fontes de gera\u00e7\u00e3o bastante diversificado, incluindo as hidrel\u00e9tricas da Bonneville Power Administration (BPA), uma grande capacidade e\u00f3lica e de gera\u00e7\u00e3o a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":998643,"template":"","meta":{"_acf_changed":false},"categories":[],"class_list":["post-1005569","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR - PSR Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR - PSR Energy\" \/>\n<meta property=\"og:description\" content=\"H\u00e1 pouco mais de dois anos, a PSR venceu uma concorr\u00eancia internacional para desenvolver um modelo avan\u00e7ado de an\u00e1lise energ\u00e9tica para a regi\u00e3o do Pacific Northwest norte americano. Esta regi\u00e3o possui um conjunto de fontes de gera\u00e7\u00e3o bastante diversificado, incluindo as hidrel\u00e9tricas da Bonneville Power Administration (BPA), uma grande capacidade e\u00f3lica e de gera\u00e7\u00e3o a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/\" \/>\n<meta property=\"og:site_name\" content=\"PSR Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psrenergy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_571445901_Preview.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"545\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@psrenergy\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/\",\"name\":\"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR - PSR Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_571445901_Preview.jpeg\",\"datePublished\":\"2022-04-28T19:00:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_571445901_Preview.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_571445901_Preview.jpeg\",\"width\":1000,\"height\":545},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticias-antigo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\",\"name\":\"PSR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#organization\"},\"alternateName\":\"PSR Energy Consulting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#organization\",\"name\":\"PSR\",\"alternateName\":\"PSR Energy Consulting\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"width\":1056,\"height\":816,\"caption\":\"PSR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/psrenergy\",\"https:\\\/\\\/x.com\\\/psrenergy\",\"https:\\\/\\\/www.instagram.com\\\/psrenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psrenergy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR - PSR Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/","og_locale":"pt_BR","og_type":"article","og_title":"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR - PSR Energy","og_description":"H\u00e1 pouco mais de dois anos, a PSR venceu uma concorr\u00eancia internacional para desenvolver um modelo avan\u00e7ado de an\u00e1lise energ\u00e9tica para a regi\u00e3o do Pacific Northwest norte americano. Esta regi\u00e3o possui um conjunto de fontes de gera\u00e7\u00e3o bastante diversificado, incluindo as hidrel\u00e9tricas da Bonneville Power Administration (BPA), uma grande capacidade e\u00f3lica e de gera\u00e7\u00e3o a [&hellip;]","og_url":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/","og_site_name":"PSR Energy","article_publisher":"https:\/\/www.facebook.com\/psrenergy","og_image":[{"width":1000,"height":545,"url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_571445901_Preview.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@psrenergy","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/","url":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/","name":"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR - PSR Energy","isPartOf":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/#primaryimage"},"image":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_571445901_Preview.jpeg","datePublished":"2022-04-28T19:00:43+00:00","breadcrumb":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/#primaryimage","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_571445901_Preview.jpeg","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_571445901_Preview.jpeg","width":1000,"height":545},{"@type":"BreadcrumbList","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/planejamento-energetico-oficial-do-sistema-do-noroeste-do-pacifico-utiliza-modelos-da-psr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psr-inc.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www.psr-inc.com\/pt-br\/noticias-antigo\/"},{"@type":"ListItem","position":3,"name":"Planejamento energ\u00e9tico oficial do sistema do noroeste do pac\u00edfico utiliza modelos da PSR"}]},{"@type":"WebSite","@id":"https:\/\/www.psr-inc.com\/pt-br\/#website","url":"https:\/\/www.psr-inc.com\/pt-br\/","name":"PSR","description":"","publisher":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#organization"},"alternateName":"PSR Energy Consulting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psr-inc.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.psr-inc.com\/pt-br\/#organization","name":"PSR","alternateName":"PSR Energy Consulting","url":"https:\/\/www.psr-inc.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.psr-inc.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","width":1056,"height":816,"caption":"PSR"},"image":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/psrenergy","https:\/\/x.com\/psrenergy","https:\/\/www.instagram.com\/psrenergy\/","https:\/\/www.linkedin.com\/company\/psrenergy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia\/1005569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia\/1005569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/media\/998643"}],"wp:attachment":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1005569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1005569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}