{"id":1005709,"date":"2023-01-19T17:35:52","date_gmt":"2023-01-19T20:35:52","guid":{"rendered":"https:\/\/novosite.psr-inc.com\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/"},"modified":"2023-01-19T17:35:52","modified_gmt":"2023-01-19T20:35:52","slug":"pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel","status":"publish","type":"noticia","link":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/","title":{"rendered":"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel"},"content":{"rendered":"<p>O Diretor Executivo, Rafael Kelman, juntamente com Tain\u00e1 Martins, consultora da PSR s\u00e3o co-autores do artigo Balancing renewable energy and river resources by moving from individual assessments of hydropower projects to energy system planning, captaniado por Jeff Opper-man (Global lead scientist for freshwater- WWF), juntamente com outros pesquisadores dos EUA, Canad\u00e1, Reino Unido, Vietn\u00e3, Col\u00f4mbia e Nepal.<\/p>\n<p>O artigo explora estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel de maneira a resguardar os diversos benef\u00edcios sociais e ambientais dos rios. As estrat\u00e9gias incluem (1) medidas individuais, como a defini\u00e7\u00e3o de vaz\u00f5es ecol\u00f3gicas, a constru\u00e7\u00e3o de es-truturas de passagem de peixes e outras medidas de mitiga\u00e7\u00e3o; (2) medidas para o conjunto de hidrel\u00e9tricas em cascata nas bacias hidrogr\u00e1ficas; (3) medidas no \u00e2mbito dos sistemas el\u00e9-tricos regionais.<\/p>\n<p>Apesar das evid\u00eancias de que o gerenciamento e a mitiga\u00e7\u00e3o individual por projeto reduzem os custos ambientais e sociais dos projetos, o artigo defende que a escala mais eficaz para buscar solu\u00e7\u00f5es equilibradas seja a de sistemas de energia por gerar mais benef\u00edcio a investi-dores, desenvolvedores e governos.<\/p>\n<p>Finalmente, o artigo tamb\u00e9m mostra, a partir de um estudo de caso na Col\u00f4mbia, que a redu-\u00e7\u00e3o de riscos e conflitos deveria fazer parte do planejamento para a sele\u00e7\u00e3o de projetos hi-drel\u00e9tricos porque melhora o resultado financeiro a investidores.<\/p>\n<p>Leia o artigo na integra no link:\u00a0<a href=\"https:\/\/www.frontiersin.org\/articles\/10.3389\/fenvs.2022.1036653\/full\">https:\/\/www.frontiersin.org\/articles\/10.3389\/fenvs.2022.1036653\/full<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Diretor Executivo, Rafael Kelman, juntamente com Tain\u00e1 Martins, consultora da PSR s\u00e3o co-autores do artigo Balancing renewable energy and river resources by moving from individual assessments of hydropower projects to energy system planning, captaniado por Jeff Opper-man (Global lead scientist for freshwater- WWF), juntamente com outros pesquisadores dos EUA, Canad\u00e1, Reino Unido, Vietn\u00e3, Col\u00f4mbia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1000340,"template":"","meta":{"_acf_changed":false},"categories":[],"class_list":["post-1005709","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel - PSR Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel - PSR Energy\" \/>\n<meta property=\"og:description\" content=\"O Diretor Executivo, Rafael Kelman, juntamente com Tain\u00e1 Martins, consultora da PSR s\u00e3o co-autores do artigo Balancing renewable energy and river resources by moving from individual assessments of hydropower projects to energy system planning, captaniado por Jeff Opper-man (Global lead scientist for freshwater- WWF), juntamente com outros pesquisadores dos EUA, Canad\u00e1, Reino Unido, Vietn\u00e3, Col\u00f4mbia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/\" \/>\n<meta property=\"og:site_name\" content=\"PSR Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psrenergy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_452790569-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@psrenergy\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/\",\"name\":\"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel - PSR Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_452790569-scaled.jpeg\",\"datePublished\":\"2023-01-19T20:35:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_452790569-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/AdobeStock_452790569-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticias-antigo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\",\"name\":\"PSR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#organization\"},\"alternateName\":\"PSR Energy Consulting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#organization\",\"name\":\"PSR\",\"alternateName\":\"PSR Energy Consulting\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"width\":1056,\"height\":816,\"caption\":\"PSR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/psrenergy\",\"https:\\\/\\\/x.com\\\/psrenergy\",\"https:\\\/\\\/www.instagram.com\\\/psrenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psrenergy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel - PSR Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/","og_locale":"pt_BR","og_type":"article","og_title":"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel - PSR Energy","og_description":"O Diretor Executivo, Rafael Kelman, juntamente com Tain\u00e1 Martins, consultora da PSR s\u00e3o co-autores do artigo Balancing renewable energy and river resources by moving from individual assessments of hydropower projects to energy system planning, captaniado por Jeff Opper-man (Global lead scientist for freshwater- WWF), juntamente com outros pesquisadores dos EUA, Canad\u00e1, Reino Unido, Vietn\u00e3, Col\u00f4mbia [&hellip;]","og_url":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/","og_site_name":"PSR Energy","article_publisher":"https:\/\/www.facebook.com\/psrenergy","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_452790569-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@psrenergy","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/","url":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/","name":"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel - PSR Energy","isPartOf":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/#primaryimage"},"image":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_452790569-scaled.jpeg","datePublished":"2023-01-19T20:35:52+00:00","breadcrumb":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/#primaryimage","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_452790569-scaled.jpeg","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/AdobeStock_452790569-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/pesquisadores-da-psr-sao-co-autores-em-artigo-internacional-sobre-estrategias-para-a-hidroeletricidade-apoiar-a-expansao-de-energia-renovavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psr-inc.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www.psr-inc.com\/pt-br\/noticias-antigo\/"},{"@type":"ListItem","position":3,"name":"Pesquisadores da PSR s\u00e3o co-autores em artigo internacional sobre estrat\u00e9gias para a hidroeletricidade apoiar a expans\u00e3o de energia renov\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/www.psr-inc.com\/pt-br\/#website","url":"https:\/\/www.psr-inc.com\/pt-br\/","name":"PSR","description":"","publisher":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#organization"},"alternateName":"PSR Energy Consulting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psr-inc.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.psr-inc.com\/pt-br\/#organization","name":"PSR","alternateName":"PSR Energy Consulting","url":"https:\/\/www.psr-inc.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.psr-inc.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","width":1056,"height":816,"caption":"PSR"},"image":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/psrenergy","https:\/\/x.com\/psrenergy","https:\/\/www.instagram.com\/psrenergy\/","https:\/\/www.linkedin.com\/company\/psrenergy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia\/1005709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia\/1005709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/media\/1000340"}],"wp:attachment":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1005709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1005709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}