{"id":1005715,"date":"2022-11-30T18:12:57","date_gmt":"2022-11-30T21:12:57","guid":{"rendered":"https:\/\/novosite.psr-inc.com\/noticia\/psr-faz-35-anos\/"},"modified":"2022-11-30T18:12:57","modified_gmt":"2022-11-30T21:12:57","slug":"psr-faz-35-anos","status":"publish","type":"noticia","link":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/","title":{"rendered":"PSR faz 35 anos!"},"content":{"rendered":"<p>A PSR, empresa de consultoria e provedora de solu\u00e7\u00f5es anal\u00edticas para o mercado de energia global, comemora 35 anos neste novembro. A PSR tem uma equipe de 130 especialistas em energia, computa\u00e7\u00e3o, engenharia, com dezenas de doutores e mestres, e atua em mais de setenta pa\u00edses de todos os continentes. Desde seu nascimento, a PSR se destaca pela inova\u00e7\u00e3o, foco em pesquisa, excel\u00eancia t\u00e9cnica, integridade e pensamento anal\u00edtico com rigor t\u00e9cnico.<\/p>\n<p>A atua\u00e7\u00e3o da PSR \u00e9 centrada no trip\u00e9 de desenvolvimento de modelos computacionais, consultoria e inova\u00e7\u00e3o. A primeira \u201cperna\u201d do trip\u00e9, modelos, surgiu em 1987 na cozinha do apartamento de seu fundador, Mario Veiga, com o software de otimiza\u00e7\u00e3o energ\u00e9tica SDDP sendo vendido para Nova Zel\u00e2ndia, Col\u00f4mbia e o mercado regional da Am\u00e9rica Central. Al\u00e9m do SDDP, que continua sendo o \u201ccarro chefe\u201d, a PSR conta atualmente com um portf\u00f3lio de softwares l\u00edderes a n\u00edvel mundial como NCP, OptFolio, OptGen, OptValue e HERA. Estes softwares s\u00e3o licenciados para mais de mil empresas no Brasil e exterior e executados no ambiente de computa\u00e7\u00e3o em nuvem PSR Cloud. Um exemplo recente \u00e9 a simula\u00e7\u00e3o energ\u00e9tica da Costa Oeste dos Estados Unidos, onde a execu\u00e7\u00e3o dos modelos \u00e9 feita em trinta mil computadores no PSR Cloud.<\/p>\n<p>&nbsp;<\/p>\n<p>A segunda \u201cperna\u201d, consultoria, come\u00e7ou em meados dos anos 1990. A PSR esteve presente em todos os marcos relevantes do setor el\u00e9trico nacional, como a assessoria \u00e0 Presid\u00eancia da Rep\u00fablica na gest\u00e3o do racionamento de energia do pa\u00eds em 2001, assessoria ao governo no desenho de contrata\u00e7\u00e3o por licita\u00e7\u00f5es em 2004, amplo apoio aos investidores em privatiza\u00e7\u00f5es e decis\u00f5es de investimento, apoio a financiadores de projetos de gera\u00e7\u00e3o, transmiss\u00e3o e distribui\u00e7\u00e3o e, mais recentemente, estudos estrat\u00e9gicos de descarboniza\u00e7\u00e3o e impacto de mudan\u00e7as clim\u00e1ticas. Esta mesma din\u00e2mica de consultoria se repetiu no exterior, onde a PSR atua em dezenas de pa\u00edses nas Am\u00e9ricas, Europa e \u00c1sia.<\/p>\n<p>&nbsp;<\/p>\n<p>A terceira \u201cperna\u201d, inova\u00e7\u00e3o, \u00e9 o esteio das atividades anteriores. As publica\u00e7\u00f5es cient\u00edficas da PSR t\u00eam mais de 9 mil cita\u00e7\u00f5es na literatura internacional, um padr\u00e3o equivalente \u00e0s melhores universidades mundiais. Esta contribui\u00e7\u00e3o foi reconhecida com a elei\u00e7\u00e3o de Mario Veiga para a US National Academy of Engineering e Academia Brasileira de Ci\u00eancias e os t\u00edtulos de Fellow do IEEE concedidos tanto para ele como para Luiz Barroso, atual diretor presidente, que tamb\u00e9m recebeu do IEEE o pr\u00eamio Outstanding Young Engineer. Adicionalmente, mais de 50 teses de doutorado e mestrado foram desenvolvidas dentro da empresa, em coorienta\u00e7\u00e3o com as melhores universidades. Um exemplo recente de inova\u00e7\u00e3o da PSR \u00e9 o software ToQUBO para otimiza\u00e7\u00e3o de sistemas de energia com computa\u00e7\u00e3o qu\u00e2ntica desenvolvido conjuntamente com o Laborat\u00f3rio de Computa\u00e7\u00e3o Qu\u00e2ntica da ag\u00eancia espacial NASA. Este ambiente desafiador e colaborativo \u00e9 um atrator de novos talentos: a idade mediana da equipe da PSR \u00e9 de apenas 28 anos, compar\u00e1vel \u00e0 de startups \u201ctech\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m de Mario Veiga e Luiz Barroso, a dire\u00e7\u00e3o executiva da PSR \u00e9 composta por Raphael Chabar e Rafael Kelman, ambos doutores em engenharia e com grande reputa\u00e7\u00e3o t\u00e9cnica em suas \u00e1reas de atua\u00e7\u00e3o. H\u00e1 dois anos a PSR deu um importante passo para seu crescimento futuro ao firmar uma parceria estrat\u00e9gica com o Banco BTG pactual. Isto vem permitindo a amplia\u00e7\u00e3o das atividades da empresa em infraestrutura, e nas \u00e1reas de inova\u00e7\u00e3o, transi\u00e7\u00e3o energ\u00e9tica, al\u00e9m de aumentar sua presen\u00e7a no mercado global de energia, mantendo sua independ\u00eancia t\u00e9cnica e de pensamento.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cNosso maior orgulho desses 35 anos \u00e9 a forma\u00e7\u00e3o das pessoas. \u00c9 um privil\u00e9gio ter convivido, aprendido, trabalhado junto e acompanhado o desenvolvimento profissional de cada um dos colaboradores dessa equipe incr\u00edvel. Muitos entraram no est\u00e1gio e hoje s\u00e3o doutores, reconhecidos no setor de energia, requisitados em grandes eventos nacionais e internacionais. \u00c9 o caso dos diretores Luiz Barroso, Raphael Chabar e Rafael Kelman, que come\u00e7aram como estagi\u00e1rios h\u00e1 mais de 20 anos.\u201d diz Mario Veiga.<\/p>\n<p>A PSR est\u00e1 pronta para os pr\u00f3ximos 35 anos, pesquisando e capacitando a equipe em novos temas como o nexo entre agroneg\u00f3cio, \u00e1gua e energia; transi\u00e7\u00e3o energ\u00e9tica e geopol\u00edtica; novas tecnologias ligadas \u00e0 economia descarbonizada; digitaliza\u00e7\u00e3o e descentraliza\u00e7\u00e3o do setor de distribui\u00e7\u00e3o; e integra\u00e7\u00e3o de informa\u00e7\u00f5es de sat\u00e9lites e Deep Reinforcement Learning na tomada de decis\u00f5es de investimento e opera\u00e7\u00e3o de sistemas de energia. E, simultaneamente, preservando nossa vis\u00e3o original de transformar ideias e m\u00e9todos em algoritmos, produtos e servi\u00e7os que beneficiem nossos clientes e, sobretudo, a sociedade.<\/p>\n<p><strong>Sobre a PSR<\/strong><\/p>\n<p>A PSR \u00e9 uma provedora global de metodologias inovadoras e ferramentas anal\u00edticas para otimiza\u00e7\u00e3o do planejamento, opera\u00e7\u00e3o e gest\u00e3o de riscos em sistemas energ\u00e9ticos e de estudos de consultoria econ\u00f4micos, financeiros e regulat\u00f3rios. Atua em mais de setenta pa\u00edses das Am\u00e9ricas, Europa, \u00c1sia-Pac\u00edfico e \u00c1frica. Seus clientes s\u00e3o investidores em eletricidade e g\u00e1s; reguladores e outras ag\u00eancias governamentais; centros de opera\u00e7\u00e3o; bancos e ag\u00eancias multilaterais de desenvolvimento como o Banco Mundial, IFC e BID; e organiza\u00e7\u00f5es ambientais, dentre muitos outros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A PSR, empresa de consultoria e provedora de solu\u00e7\u00f5es anal\u00edticas para o mercado de energia global, comemora 35 anos neste novembro. A PSR tem uma equipe de 130 especialistas em energia, computa\u00e7\u00e3o, engenharia, com dezenas de doutores e mestres, e atua em mais de setenta pa\u00edses de todos os continentes. Desde seu nascimento, a PSR [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":998765,"template":"","meta":{"_acf_changed":false},"categories":[],"class_list":["post-1005715","noticia","type-noticia","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PSR faz 35 anos! - PSR Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PSR faz 35 anos! - PSR Energy\" \/>\n<meta property=\"og:description\" content=\"A PSR, empresa de consultoria e provedora de solu\u00e7\u00f5es anal\u00edticas para o mercado de energia global, comemora 35 anos neste novembro. A PSR tem uma equipe de 130 especialistas em energia, computa\u00e7\u00e3o, engenharia, com dezenas de doutores e mestres, e atua em mais de setenta pa\u00edses de todos os continentes. Desde seu nascimento, a PSR [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"PSR Energy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/psrenergy\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/Untitled-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"941\" \/>\n\t<meta property=\"og:image:height\" content=\"481\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@psrenergy\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/\",\"name\":\"PSR faz 35 anos! - PSR Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Untitled-2.png\",\"datePublished\":\"2022-11-30T21:12:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Untitled-2.png\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Untitled-2.png\",\"width\":941,\"height\":481},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticia\\\/psr-faz-35-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcias\",\"item\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/noticias-antigo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PSR faz 35 anos!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\",\"name\":\"PSR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#organization\"},\"alternateName\":\"PSR Energy Consulting\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#organization\",\"name\":\"PSR\",\"alternateName\":\"PSR Energy Consulting\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"contentUrl\":\"https:\\\/\\\/www.psr-inc.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-psr.svg\",\"width\":1056,\"height\":816,\"caption\":\"PSR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.psr-inc.com\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/psrenergy\",\"https:\\\/\\\/x.com\\\/psrenergy\",\"https:\\\/\\\/www.instagram.com\\\/psrenergy\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/psrenergy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PSR faz 35 anos! - PSR Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"PSR faz 35 anos! - PSR Energy","og_description":"A PSR, empresa de consultoria e provedora de solu\u00e7\u00f5es anal\u00edticas para o mercado de energia global, comemora 35 anos neste novembro. A PSR tem uma equipe de 130 especialistas em energia, computa\u00e7\u00e3o, engenharia, com dezenas de doutores e mestres, e atua em mais de setenta pa\u00edses de todos os continentes. Desde seu nascimento, a PSR [&hellip;]","og_url":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/","og_site_name":"PSR Energy","article_publisher":"https:\/\/www.facebook.com\/psrenergy","og_image":[{"width":941,"height":481,"url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/Untitled-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@psrenergy","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/","url":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/","name":"PSR faz 35 anos! - PSR Energy","isPartOf":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/Untitled-2.png","datePublished":"2022-11-30T21:12:57+00:00","breadcrumb":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/#primaryimage","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/Untitled-2.png","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2025\/08\/Untitled-2.png","width":941,"height":481},{"@type":"BreadcrumbList","@id":"https:\/\/www.psr-inc.com\/pt-br\/noticia\/psr-faz-35-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psr-inc.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcias","item":"https:\/\/www.psr-inc.com\/pt-br\/noticias-antigo\/"},{"@type":"ListItem","position":3,"name":"PSR faz 35 anos!"}]},{"@type":"WebSite","@id":"https:\/\/www.psr-inc.com\/pt-br\/#website","url":"https:\/\/www.psr-inc.com\/pt-br\/","name":"PSR","description":"","publisher":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#organization"},"alternateName":"PSR Energy Consulting","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psr-inc.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.psr-inc.com\/pt-br\/#organization","name":"PSR","alternateName":"PSR Energy Consulting","url":"https:\/\/www.psr-inc.com\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.psr-inc.com\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","contentUrl":"https:\/\/www.psr-inc.com\/wp-content\/uploads\/2023\/03\/logo-psr.svg","width":1056,"height":816,"caption":"PSR"},"image":{"@id":"https:\/\/www.psr-inc.com\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/psrenergy","https:\/\/x.com\/psrenergy","https:\/\/www.instagram.com\/psrenergy\/","https:\/\/www.linkedin.com\/company\/psrenergy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia\/1005715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/noticia\/1005715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/media\/998765"}],"wp:attachment":[{"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1005715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.psr-inc.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1005715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}